{"id":252683,"date":"2026-05-26T16:58:56","date_gmt":"2026-05-26T15:58:56","guid":{"rendered":"https:\/\/zoca.es\/producto\/impressora-pos-termica-epson-tm-m30ii-nueva-novo-pt-15236\/"},"modified":"2026-06-15T17:35:44","modified_gmt":"2026-06-15T15:35:44","slug":"impressora-pos-termica-epson-tm-m30ii-nueva-novo-pt-15236","status":"publish","type":"product","link":"https:\/\/zoca.es\/pt-pt\/produto\/impressora-pos-termica-epson-tm-m30ii-nueva-novo-pt-15236\/","title":{"rendered":"Impressora POS T\u00e9rmica Epson TM-M30II &#8211; NUEVA | Novo"},"content":{"rendered":"<p><strong>Tecnologia<\/strong><br \/>T\u00e9rmica<br \/><strong>C\u00f3pias<\/strong><br \/>Velocidade de impress\u00e3o 250 mm\/s<br \/>Caracteres por polegada 203<br \/><strong>Manuseio de papel<\/strong><br \/>Largura do papel 79.5mm<br \/>Corte autom\u00e1tico<br \/><strong>Conectividade impressora<\/strong><br \/>USB, Rede, Abertura gaveta<br \/><strong>Dimens\u00f5es<\/strong><br \/>12.7&#215;12.7&#215;13.5 cm.<br \/><strong>Peso<\/strong><br \/>1.30 Kg.<br \/><strong>Especifica\u00e7\u00f5es adicionais<\/strong><br \/>A Epson TM-M30II \u00e9 uma impressora POS t\u00e9rmica concebida para lojas, balc\u00f5es e ambientes profissionais que necessitam de uma solu\u00e7\u00e3o compacta, r\u00e1pida e fi\u00e1vel para a impress\u00e3o di\u00e1ria. Trabalha com uma largura de papel de 79,5 mm, adequada para tal\u00f5es, recibos e documenta\u00e7\u00e3o comercial habitual em pontos de venda. O seu sistema de corte autom\u00e1tico facilita uma utiliza\u00e7\u00e3o c\u00f3moda e \u00e1gil, reduzindo interven\u00e7\u00f5es manuais e melhorando o ritmo de trabalho em opera\u00e7\u00f5es cont\u00ednuas. Oferece uma velocidade de impress\u00e3o de 250 mm\/s, pensada para manter uma resposta r\u00e1pida mesmo em momentos de alta atividade. A sua resolu\u00e7\u00e3o de 203 caracteres por polegada proporciona uma impress\u00e3o clara para textos, c\u00f3digos e refer\u00eancias habituais em processos de venda ou gest\u00e3o. Incorpora conectividade USB, Rede e abertura de gaveta, facilitando a sua integra\u00e7\u00e3o em sistemas POS e configura\u00e7\u00f5es profissionais de caixa. <b>Tecnologia NFC integrada:<\/b> permite identificar e selecionar rapidamente a impressora aproximando um dispositivo compat\u00edvel da \u00e1rea NFC. N\u00e3o substitui o Bluetooth, USB ou Ethernet; simplesmente simplifica a configura\u00e7\u00e3o e o emparelhamento r\u00e1pido em ambientes de POS (Ponto de Venda).&nbsp;<br \/>A sua carca\u00e7a em cor preta oferece uma presen\u00e7a s\u00f3bria, discreta e profissional, adequada para espa\u00e7os comerciais atuais. \u00c9 uma op\u00e7\u00e3o interessante para quem procura uma impressora t\u00e9rmica POS eficiente, vers\u00e1til e preparada para se integrar no fluxo di\u00e1rio de trabalho.<br \/><b>Produto Novo. Embalagem Original.<\/b>&nbsp;Veja &#8220;+ Fotos&#8221; e se tiver alguma d\u00favida contacte-nos ou utilize o nosso chat para mais informa\u00e7\u00f5es ou para pedir mais detalhes.<br \/><strong>Coment\u00e1rios<\/strong><br \/><u>Tecnologia de comunica\u00e7\u00e3o NFC Near Field &#8211; embalagem original<\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00e9rmica \u00b7 Largura do papel 79.5mm \u00b7 Corte autom\u00e1tico \u00b7 Velocidade de impress\u00e3o 250 mm\/s \u00b7 Caracteres por polegada 203 \u00b7 USB, Rede, Abertura gaveta \u00b7 Caixa cor preto \u00b7<br \/>\n<strong>Tecnologia de comunica\u00e7\u00e3o NFC Near Field &#8211; embalagem original<\/strong><\/p>\n","protected":false},"featured_media":252663,"template":"","meta":[],"product_brand":[3472],"product_cat":[2362,3117,61,2389],"product_tag":[],"class_list":["post-252683","product","type-product","status-publish","has-post-thumbnail","product_brand-epson","product_cat-impressoras-pt","product_cat-pos-impressoras-pt","product_cat-pos-pt","product_cat-impressoras-pos-pt","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":12,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":[],"addons":[],"df_price":277.09,"df_sale_price":"","df_regular_price":277.09,"df_image_link":"https:\/\/zoca.es\/wp-content\/uploads\/images\/product\/15236\/epso00069_01-300x225.jpg","_links":{"self":[{"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/product\/252683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/media\/252663"}],"wp:attachment":[{"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=252683"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=252683"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=252683"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zoca.es\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=252683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}